{"id":13183,"date":"2020-10-13T17:54:58","date_gmt":"2020-10-13T20:54:58","guid":{"rendered":"https:\/\/www.editorasolucao.com.br\/blog\/?post_type=concurso&#038;p=13183"},"modified":"2020-10-20T09:19:16","modified_gmt":"2020-10-20T12:19:16","slug":"prefeitura-de-amargosa-ba","status":"publish","type":"concurso","link":"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-amargosa-ba","title":{"rendered":"Concurso Prefeitura de Amargosa &#8211; BA 2020: 39 vagas abertas! Confira!"},"content":{"rendered":"\n<p>Foi divulgado o <a rel=\"noreferrer noopener\" aria-label=\"Edital (abre em uma nova aba)\" href=\"https:\/\/www.editorasolucao.com.br\" target=\"_blank\">Edital<\/a> do <strong>Concurso Prefeitura de Amargosa<\/strong>, no estado da <a href=\"https:\/\/www.editorasolucao.com.br\/blog\/concursos-abertos-ba\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Bahia (abre em uma nova aba)\">Bahia<\/a>, que oferece <strong>39 vagas imediatas para candidatos de n\u00edvel Superior<\/strong>, com sal\u00e1rios que chegam a <strong>R$ 9,4 mil<\/strong>. Confira os detalhes ao decorrer do texto.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_69_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Menu de navega&ccedil;&atilde;o<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-amargosa-ba\/#Inscricoes_do_Concurso_de_Amargosa_%E2%80%93_BA\" title=\"Inscri\u00e7\u00f5es do Concurso de Amargosa \u2013 BA\">Inscri\u00e7\u00f5es do Concurso de Amargosa \u2013 BA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-amargosa-ba\/#Cargos_vagas_e_salarios_do_Concurso_Prefeitura_de_Amargosa_%E2%80%93_BA\" title=\"Cargos, vagas e sal\u00e1rios do Concurso Prefeitura de Amargosa \u2013 BA\">Cargos, vagas e sal\u00e1rios do Concurso Prefeitura de Amargosa \u2013 BA<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-amargosa-ba\/#Quais_sao_os_requisitos_basicos_para_a_investidura_nos_cargos_do_Concurso_de_Amargosa_%E2%80%93_BA\" title=\"Quais s\u00e3o os requisitos b\u00e1sicos para a investidura nos cargos do Concurso de Amargosa \u2013 BA?\">Quais s\u00e3o os requisitos b\u00e1sicos para a investidura nos cargos do Concurso de Amargosa \u2013 BA?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-amargosa-ba\/#Como_serao_as_provas_do_Concurso_Prefeitura_de_Amargosa_%E2%80%93_BA\" title=\"Como ser\u00e3o as provas do Concurso Prefeitura de Amargosa \u2013 BA?\">Como ser\u00e3o as provas do Concurso Prefeitura de Amargosa \u2013 BA?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-amargosa-ba\/#Sobre_Amargosa_%E2%80%93_BA\" title=\"Sobre Amargosa \u2013 BA\">Sobre Amargosa \u2013 BA<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Inscricoes_do_Concurso_de_Amargosa_%E2%80%93_BA\"><\/span>Inscri\u00e7\u00f5es do Concurso de Amargosa \u2013 BA<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>As inscri\u00e7\u00f5es devem ser realizadas atrav\u00e9s do site da banca organizadora <a href=\"http:\/\/www.fundacaocefetbahia.org.br\/amargosa\/2020\/concursopublico_ns\/concurso_ns.asp\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Funda\u00e7\u00e3o CefetBahia (abre em uma nova aba)\">Funda\u00e7\u00e3o CefetBahia<\/a>, at\u00e9 \u00e0s<strong> 23h59 do dia 29 de outubro de 2020<\/strong>. Para efetuar a inscri\u00e7\u00e3o \u00e9 necess\u00e1rio pagar uma taxa no valor de <strong>R$ 95,00<\/strong>.<\/p>\n\n\n\n<head>\n<style>\nbutton.css3button {\nfont-family: Arial, Helvetica, sans-serif;\nfont-size: 20px;\ncolor: #ffffff!important;\npadding: 12px 25px;\nbackground: -webkit-gradient(\nlinear, left top, left bottom,\nfrom(#0091ff),\nto(#037efa));\nbackground: linear-gradient(\ntop,\n#0091ff 0%,\n#037efa);\nborder-radius: 8px;\nborder: 0px solid #000000;\nbox-shadow:\n0px 4px 0px rgba(0,111,214,1),\ninset 0px 0px 1px rgba(84,84,84,0.5);\ntext-shadow:\n0px 0px 0px rgba(000,000,000,0.7),\n0px 0px 0px rgba(255,255,255,0.9);\n}\n\n<\/style>\n<\/head>\n<center><button type=\"button\" name=\"\" value=\"\" class=\"css3button\"><a data-cat=\"link-botao\" style=\"color:#ffffff!important; text-decoration:none;\" href=\"https:\/\/www.editorasolucao.com.br\/concurso\/prefeitura-de-amargosa-ba\" target=\"_blank\"><strong><span style=\"color:#ffffff;\">Clique e Comece seus Estudos!<\/span><\/a><\/strong><\/button><\/center><br\/>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cargos_vagas_e_salarios_do_Concurso_Prefeitura_de_Amargosa_%E2%80%93_BA\"><\/span>Cargos, vagas e sal\u00e1rios do Concurso Prefeitura de Amargosa \u2013 BA<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>S\u00e3o ofertadas <strong>39 vagas imediatas para candidatos de n\u00edvel Superio<\/strong>r, com sal\u00e1rios que v\u00e3o de <strong>R$ 1.772,78 a R$ 9.454,86<\/strong> e jornadas de trabalho que variam de 20 a 40 horas semanais. Abaixo est\u00e3o a quantidade de oportunidades correspondentes a cada fun\u00e7\u00e3o. <\/p>\n\n\n\n<p>Analista Administrativo (2), Analista de Controle Interno (1); Analista de Compras P\u00fablicas (2); Analista em Gest\u00e3o de Pessoas (1); Assistente Social (3); Auditor da Receita Municipal (1); Auditor em Sa\u00fade &#8211; M\u00e9dico (1); Bi\u00f3logo (1); Enfermeiro (4); Farmac\u00eautico (1); M\u00e9dico (7); M\u00e9dico Pediatra (1); Nutricionista (1); Odont\u00f3logo (7); Psic\u00f3logo (5) e Sanitarista &#8211; Enfermeiro (1).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quais_sao_os_requisitos_basicos_para_a_investidura_nos_cargos_do_Concurso_de_Amargosa_%E2%80%93_BA\"><\/span>Quais s\u00e3o os requisitos b\u00e1sicos para a investidura nos cargos do Concurso de Amargosa \u2013 BA?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Saiba quais s\u00e3o as exig\u00eancias para que o candidato tome posse dos cargos ofertados:<\/p>\n\n\n\n<ul><li>ter sido aprovado e classificado no Concurso P\u00fablico, na forma do edital; <\/li><li> idade m\u00ednima de 18 (dezoito) anos; <\/li><li> ter aptid\u00e3o f\u00edsica e mental para o exerc\u00edcio das atribui\u00e7\u00f5es do cargo; <\/li><li> apresentar os documentos comprobat\u00f3rios da escolaridade e requisitos constantes no item do Edital. <\/li><li> ter nacionalidade brasileira ou equiparada; <\/li><li> estar em pleno gozo e exerc\u00edcio dos direitos pol\u00edticos; <\/li><li> apresentar declara\u00e7\u00e3o de ac\u00famulo de cargos ou negativa de acumula\u00e7\u00e3o; <\/li><li> atender \u00e0s demais exig\u00eancias contidas no Edital.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"text-align:center\"><strong><a data-cat=\"link-artigo-corpo\" href=\"https:\/\/www.editorasolucao.com.br\/concurso\/prefeitura-de-amargosa-ba\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Estude com as Apostilas Prefeitura de Amargosa - BA e parcele SEM JUROS (abre em uma nova aba)\">Estude com as Apostilas Prefeitura de Amargosa &#8211; BA e parcele SEM JUROS<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_serao_as_provas_do_Concurso_Prefeitura_de_Amargosa_%E2%80%93_BA\"><\/span>Como ser\u00e3o as provas do Concurso Prefeitura de Amargosa \u2013 BA?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O certame ser\u00e1 composto de <strong>duas etapas<\/strong>. S\u00e3o elas:<\/p>\n\n\n\n<ul><li><strong>Prova Objetiva<\/strong>, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio; e<\/li><li> <strong>Prova de T\u00edtulos<\/strong>, de car\u00e1ter classificat\u00f3rio. <\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Prova Objetiva<\/h4>\n\n\n\n<p>A <strong>Prova Objetiva<\/strong> est\u00e1 prevista para ser realizada no dia <strong>13 de dezembro de 2020<\/strong>, tendo dura\u00e7\u00e3o de 02 horas e contar\u00e1 com 30 quest\u00f5es de m\u00faltipla escolha, sendo 20 quest\u00f5es de Conhecimentos Gerais e 10 quest\u00f5es de Conhecimentos Espec\u00edficos. Abaixo est\u00e3o a as disciplinas que versar\u00e3o as provas:<\/p>\n\n\n\n<p><strong>Conhecimentos Gerais:<\/strong><\/p>\n\n\n\n<ul><li>L\u00edngua Portuguesa;<\/li><li> Inform\u00e1tica b\u00e1sica e aplicada;<\/li><li> Contexto e realidade socioecon\u00f4mico local do munic\u00edpio de Amargosa;<\/li><li>  Racioc\u00ednio L\u00f3gico; <\/li><li> Administra\u00e7\u00e3o P\u00fablica; <\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Conhecimentos Espec\u00edficos. <\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Prova de T\u00edtulos<\/h4>\n\n\n\n<p>A <strong>Prova de T\u00edtulos<\/strong> \u00e9 destinada apenas para os aprovados na fase escrita. Essa avalia\u00e7\u00e3o baseada nos documentos de forma\u00e7\u00e3o acad\u00eamica e experi\u00eancia profissional que devem ser enviados pelo site da banca. Os crit\u00e9rios de pontua\u00e7\u00e3o variam conforme o cargo pretendido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sobre_Amargosa_%E2%80%93_BA\"><\/span>Sobre Amargosa \u2013 BA<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Em 19 de junho de 1891, aconteceu o ato de cria\u00e7\u00e3o que elevou a Vila de Nossa Senhora do Bom Conselho de Amargosa \u00e0 categoria de cidade, passando a se chamar apenas Amargosa. O nome desta cidade teve origem na ca\u00e7a das pombas de carne amarga que faziam parte da fauna local, onde havia uma tribo ind\u00edgena cujo nome era &#8220;Baitinga&#8221; cujos \u00edndios atra\u00eddos pela ca\u00e7a na regi\u00e3o, costumavam convidar seus companheiros usando a express\u00e3o &#8220;vamos \u00e0s amargosas?&#8221;. Amargosa \u00e9 um munic\u00edpio que se destaca pela beleza de suas in\u00fameras pra\u00e7as e jardins. Amargosa tem como um de seus mais ilustres personagens Pedro Calmon, que foi muito importante para o desenvolvimento da cidade.<\/p>\n\n\n\n<p>Situada no Vale do Jiquiri\u00e7\u00e1, em uma das mais belas paisagens do interior da Bahia, que incluem rios, cachoeiras, matas e trilhas. Possui um dos quatro melhores \u00edndices de sa\u00fade da Bahia, a cidade melhora sua infraestrutura e vem crescendo economicamente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"text-align:center\"><strong>Conte\u00fado Program\u00e1tico<\/strong><\/p>\n\n\n\n<ul><li>L\u00edngua Portuguesa: Leitura e interpreta\u00e7\u00e3o de textos (ficcionais e\/ou n\u00e3o ficcionais); Ortografia, acentua\u00e7\u00e3o, pontua\u00e7\u00e3o; Forma\u00e7\u00e3o de palavras. L\u00e9xico: adequa\u00e7\u00e3o no emprego das palavras. Verbos: conjuga\u00e7\u00e3o, emprego dos tempos, modos e vozes verbais; as palavras de rela\u00e7\u00e3o; morfossintaxe; estrutura do per\u00edodo, da ora\u00e7\u00e3o e da frase; concord\u00e2ncia nominal e verbal; reg\u00eancia nominal e verbal; coloca\u00e7\u00e3o pronominal; formas de tratamento (usos e adequa\u00e7\u00f5es). Estrutura do par\u00e1grafo. Coes\u00e3o e coer\u00eancia textuais; Estil\u00edstica: denota\u00e7\u00e3o e conota\u00e7\u00e3o; figuras de linguagem. N\u00edveis de linguagem. Sem\u00e2ntica: sinon\u00edmia, anton\u00edmia, homon\u00edmia, paron\u00edmia, polissemia e figuras de linguagem. Reda\u00e7\u00e3o oficial (of\u00edcio, memorando, ata, parecer). <\/li><li> Inform\u00e1tica b\u00e1sica e aplicada: Inform\u00e1tica b\u00e1sica. Hardwares e perif\u00e9ricos. Windows 10 Pro: painel de controle. Microsoft Office 365: Word, Excel, Power Point, Outlook. Internet. Intranet Browsers. Sites de busca. Correio eletr\u00f4nico. Backup: conceitos b\u00e1sicos, tipos, dispositivos e ferramentas, unidades de medida de armazenamento, compacta\u00e7\u00e3o de arquivos. V\u00edrus e programas maliciosos: conceitos b\u00e1sicos, tipos, a\u00e7\u00f5es preventivas\/corretivas e softwares de seguran\u00e7a digital. Redes sociais. No\u00e7\u00f5es sobre redes e Wi-Fi.<\/li><li>  Contexto e realidade socioecon\u00f4mico local do munic\u00edpio de Amargosa: Hist\u00f3rico do munic\u00edpio, cultura, economia geografia, pol\u00edtica local e atualidades. Normas gerais e crit\u00e9rios b\u00e1sicos para a promo\u00e7\u00e3o e incentivos \u00e0 Inova\u00e7\u00e3o, objetivando ambientes produtivos e regras para implementa\u00e7\u00e3o da Cidade Inteligente (Smart City) no \u00e2mbito do mun\u00edcipio de Amargosa (Lei n\u00ba 582, de 21 de agosto de 2020). <\/li><li> Racioc\u00ednio l\u00f3gico: Proposi\u00e7\u00f5es. Senten\u00e7as abertas. Argumentos. Diagrama de Euler. Operadores l\u00f3gicos. Tabelas-verdade. Tautologia. Contradi\u00e7\u00e3o. Conting\u00eancia. Equival\u00eancia l\u00f3gica. Validade dos argumentos.<\/li><li>  Administra\u00e7\u00e3o P\u00fablica: Constitui\u00e7\u00e3o Federal: art. 37 a 40. Estatuto do Servidor do Munic\u00edpio de Amargosa (Lei n\u00ba 8, de 02 de mar\u00e7o de 2006 e Lei complementar n\u00ba 35, de 19 de agosto de 2020). Poderes administrativos. Princ\u00edpios norteadores dos Servi\u00e7os P\u00fablicos. Processo Administrativo. Atos administrativos. Lei da improbidade administrativa (Lei n\u00ba 8.429, de 2 de junho de 1992). Crimes contra Administra\u00e7\u00e3o p\u00fablica.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>Conferiu todo o texto? Deseja fazer o certame? Ent\u00e3o comece a se preparar com as <strong>Apostilas Solu\u00e7\u00e3o<\/strong> e tenha um resultado positivo! <strong>Bons estudos e boa prova!!!<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong><a data-cat=\"link-rodape\" href=\"https:\/\/www.editorasolucao.com.br\/concurso\/prefeitura-de-amargosa-ba\" target=\"_blank\" rel=\"noreferrer noopener\">Estude com as Apostilas Prefeitura de Amargosa &#8211; BA e parcele SEM JUROS<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi divulgado o Edital do Concurso Prefeitura de Amargosa, no estado da Bahia, que oferece 39 vagas imediatas para candidatos de n\u00edvel Superior, com sal\u00e1rios que chegam a R$ 9,4 mil. Confira os detalhes ao decorrer do texto. Inscri\u00e7\u00f5es do Concurso de Amargosa \u2013 BA As inscri\u00e7\u00f5es devem ser realizadas atrav\u00e9s do site da banca organizadora Funda\u00e7\u00e3o CefetBahia, at\u00e9 \u00e0s 23h59 do dia 29 de outubro de 2020. Para efetuar a inscri\u00e7\u00e3o \u00e9 necess\u00e1rio pagar uma taxa no valor de R$ 95,00. Clique e Comece seus Estudos! Cargos, vagas e sal\u00e1rios do Concurso Prefeitura de Amargosa \u2013 BA S\u00e3o ofertadas&#8230;<\/p>\n","protected":false},"author":7,"featured_media":13185,"template":"","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false},"categories":[],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/concurso\/13183"}],"collection":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/concurso"}],"about":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/types\/concurso"}],"author":[{"embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/media\/13185"}],"wp:attachment":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/media?parent=13183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/categories?post=13183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/tags?post=13183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}