{"id":1990,"date":"2019-02-21T14:10:31","date_gmt":"2019-02-21T17:10:31","guid":{"rendered":"https:\/\/www.editorasolucao.com.br\/blog\/?post_type=concurso&#038;p=1990"},"modified":"2019-04-17T16:28:21","modified_gmt":"2019-04-17T19:28:21","slug":"iss-manaus","status":"publish","type":"concurso","link":"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/iss-manaus","title":{"rendered":"Concurso ISS Manaus 2019: Saiu edital com sal\u00e1rios de at\u00e9 R$ 17,4 mil!"},"content":{"rendered":"\n<p>Sa\u00edram os editais do concurso da Secretaria Municipal de Finan\u00e7as, Tecnologia da Informa\u00e7\u00e3o e Controle Interno de Manaus<strong> (Concurso ISS Manaus) <\/strong>com a oferta de <strong>50 vagas<\/strong> no total para v\u00e1rios cargos e sal\u00e1rios que chegam a<strong> R$ 17,4 mil<\/strong>!<\/p>\n\n\n\n<p style=\"text-align:center\"><strong><a href=\"https:\/\/www.editorasolucao.com.br\/catalogsearch\/result\/?q=semef-am&amp;cat=\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Estude com a Apostila ISS Manaus 2019 e parcele SEM JUROS (abre em uma nova aba)\">Estude com a Apostila ISS Manaus 2019 e parcele SEM JUROS<\/a><\/strong><\/p>\n\n\n\n<p>Para participar deste certame, voc\u00ea dever\u00e1 acessar o site da organizadora, <strong><a rel=\"noreferrer noopener\" aria-label=\"FCC (abre em uma nova aba)\" href=\"https:\/\/www.concursosfcc.com.br\/concursos\/semef118\/index.html\" target=\"_blank\">FCC<\/a><\/strong>, a partir do dia <strong>25 de fevereiro at\u00e9 o dia 12 de abril de 2019<\/strong>. As taxas variam de <strong>R$ 125,00<\/strong> (m\u00e9dio), <strong>R$ 200,00<\/strong> (superior) e <strong>R$ 265,00<\/strong> para o cargo de Auditor Fiscal.<br><\/p>\n\n\n\n<p>Confira todos os detalhes sobre o concurso para que voc\u00ea possa iniciar sua prepara\u00e7\u00e3o.<br><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_69_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Menu de navega&ccedil;&atilde;o<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/iss-manaus\/#Cargos_vagas_e_salarios_do_concurso_ISS_Manaus\" title=\"Cargos, vagas e sal\u00e1rios do concurso ISS Manaus\">Cargos, vagas e sal\u00e1rios do concurso ISS Manaus<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/iss-manaus\/#Como_serao_as_provas_do_concurso_SEMEF_2019\" title=\"Como ser\u00e3o as provas do concurso SEMEF 2019?\">Como ser\u00e3o as provas do concurso SEMEF 2019?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cargos_vagas_e_salarios_do_concurso_ISS_Manaus\"><\/span><strong>Cargos, vagas e sal\u00e1rios do concurso ISS Manaus<\/strong><br><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>As 50 oportunidades deste concurso est\u00e3o divididas em dois editais conforme abaixo:<br><\/p>\n\n\n\n<p><strong>Edital 01\/2019: <\/strong>Auditor Fiscal de Tributos Municipais (10 vagas).<br><\/p>\n\n\n\n<p>A remunera\u00e7\u00e3o inicial para Auditor \u00e9 de <strong>R$ 17.436,29<\/strong>. Para se candidatar a vaga \u00e9 preciso ter ensino <strong>superior completo em qualquer \u00e1rea de forma\u00e7\u00e3o<\/strong>.<br><\/p>\n\n\n\n<p><strong>Edital 02\/2019: <\/strong><br><\/p>\n\n\n\n<p><strong>N\u00edvel superior: <\/strong><a data-cat=\"link-artigo-cargo\" href=\"https:\/\/www.editorasolucao.com.br\/apostila-solucao\/impresso\/apostila-semef-am-2019-tecnico-fazendeiro\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"T\u00e9cnico Fazend\u00e1rio (abre em uma nova aba)\">T\u00e9cnico Fazend\u00e1rio<\/a> (02 vagas e superior em qualquer \u00e1rea); T\u00e9cnico de TI (08); T\u00e9cnico de Web Design (01). Sal\u00e1rios de <strong>R$ 13.193,77<\/strong>.<br><\/p>\n\n\n\n<p><strong>N\u00edvel m\u00e9dio: <\/strong><a data-cat=\"link-artigo-cargo\" href=\"https:\/\/www.editorasolucao.com.br\/apostila-solucao\/impresso\/apostila-semef-am-2019-assistente-tecnico-fazendeiro\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Assistente T\u00e9cnico Fazend\u00e1rio (abre em uma nova aba)\">Assistente T\u00e9cnico Fazend\u00e1rio<\/a> (5); Assistente T\u00e9cnico de TI \u2013 <a data-cat=\"link-artigo-cargo\" rel=\"noreferrer noopener\" aria-label=\"Programador  (abre em uma nova aba)\" href=\"https:\/\/www.editorasolucao.com.br\/apostila-solucao\/impresso\/apostila-semef-am-2019-tecnico-ti-assistente-tecnico-ti-programador-suporte\" target=\"_blank\">Programador <\/a>(12); Assistente T\u00e9cnico de TI \u2013 <a rel=\"noreferrer noopener\" aria-label=\" (abre em uma nova aba)\" href=\"https:\/\/www.editorasolucao.com.br\/apostila-solucao\/impresso\/apostila-semef-am-2019-tecnico-ti-assistente-tecnico-ti-programador-suporte\" target=\"_blank\">Suporte <\/a>(12). Iniciais de <strong>R$ 8.211,81<\/strong>.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_serao_as_provas_do_concurso_SEMEF_2019\"><\/span><strong>Como ser\u00e3o as provas do concurso SEMEF 2019?<\/strong><br><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Todos os candidatos ser\u00e3o submetidos a provas objetivas a serem aplicadas em dias distintos:<br><\/p>\n\n\n\n<p><strong>19\/05<\/strong> \u2013 Auditor Fiscal (prova discursiva aplicada no dia <strong>04\/08<\/strong>) e Assistente T\u00e9cnico Fazend\u00e1rio.<br><strong>26\/05 <\/strong>&#8211; Assistente T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o da Fazenda Municipal \u2013 Programador; Assistente T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o da Fazenda Municipal \u2013 Suporte; T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o da Fazenda Municipal e T\u00e9cnico em Web Design da Fazenda Municipal.<br><strong>02\/06<\/strong> &#8211; T\u00e9cnico Fazend\u00e1rio.<br><\/p>\n\n\n\n<p>Haver\u00e1 ainda <strong>prova discursiva<\/strong> para todos os cargos exceto para Assistente T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o da Fazenda Municipal \u2013 Programador e Assistente T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o da Fazenda Municipal \u2013 Suporte.<br><\/p>\n\n\n\n<p>As provas objetivas para o cargo de <strong>Auditor Fiscal <\/strong>ser\u00e3o compostas por:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"193\" src=\"https:\/\/www.editorasolucao.com.br\/blog\/wp-content\/uploads\/2019\/02\/iss1-1.png\" alt=\"\" class=\"wp-image-1992\"\/><\/figure><\/div>\n\n\n\n<p>J\u00e1 as provas para os <strong>demais cargos<\/strong> ser\u00e3o compostas da seguinte forma:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"251\" src=\"https:\/\/www.editorasolucao.com.br\/blog\/wp-content\/uploads\/2019\/02\/iss2.png\" alt=\"\" class=\"wp-image-1993\"\/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\"><strong><a href=\"https:\/\/www.editorasolucao.com.br\/catalogsearch\/result\/?q=semef-am&amp;cat=\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Estude com a Apostila ISS Manaus 2019 e parcele SEM JUROS (abre em uma nova aba)\">Estude com a Apostila ISS Manaus 2019 e parcele SEM JUROS<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sa\u00edram os editais do concurso da Secretaria Municipal de Finan\u00e7as, Tecnologia da Informa\u00e7\u00e3o e Controle Interno de Manaus (Concurso ISS Manaus) com a oferta de 50 vagas no total para v\u00e1rios cargos e sal\u00e1rios que chegam a R$ 17,4 mil! Estude com a Apostila ISS Manaus 2019 e parcele SEM JUROS Para participar deste certame, voc\u00ea dever\u00e1 acessar o site da organizadora, FCC, a partir do dia 25 de fevereiro at\u00e9 o dia 12 de abril de 2019. As taxas variam de R$ 125,00 (m\u00e9dio), R$ 200,00 (superior) e R$ 265,00 para o cargo de Auditor Fiscal. Confira todos os&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1997,"template":"","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false},"categories":[],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/concurso\/1990"}],"collection":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/concurso"}],"about":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/types\/concurso"}],"author":[{"embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/media\/1997"}],"wp:attachment":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}