{"id":2048,"date":"2024-04-12T10:06:25","date_gmt":"2024-04-12T13:06:25","guid":{"rendered":"https:\/\/www.editorasolucao.com.br\/blog\/?post_type=concurso&#038;p=2048"},"modified":"2024-04-23T10:47:25","modified_gmt":"2024-04-23T13:47:25","slug":"prefeitura-de-parnamirim-rn","status":"publish","type":"concurso","link":"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-parnamirim-rn","title":{"rendered":"Concurso Prefeitura de Parnamirim: Edital publicado para Guarda Municipal. 150 vagas!"},"content":{"rendered":"\n<p>Ol\u00e1 concurseiros do Rio Grande do Norte! Foi publicado o edital do <strong>concurso Prefeitura de Parnamirim<\/strong>, que oferta 150 vagas para provimento imediato e para forma\u00e7\u00e3o de cadastro reserva para o cargo de Guarda. Se interessa pelo certame? Fique e confira os demais detalhes no decorrer da not\u00edcia. \ud83d\ude09<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_69_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Menu de navega&ccedil;&atilde;o<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-parnamirim-rn\/#Como_posso_me_inscrever_no_concurso_Prefeitura_de_Parnamirim\" title=\"Como posso me inscrever no concurso Prefeitura de Parnamirim?\">Como posso me inscrever no concurso Prefeitura de Parnamirim?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-parnamirim-rn\/#Quantas_vagas_estao_sendo_ofertadas_no_concurso_prefeitura_de_Parnamirim-RN\" title=\"Quantas vagas est\u00e3o sendo ofertadas no concurso prefeitura de Parnamirim-RN?\">Quantas vagas est\u00e3o sendo ofertadas no concurso prefeitura de Parnamirim-RN?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-parnamirim-rn\/#Quais_sao_os_requisitos_para_participar_do_concurso_Prefeitura_de_Parnamirim\" title=\"Quais s\u00e3o os requisitos para participar do concurso Prefeitura de Parnamirim?\">Quais s\u00e3o os requisitos para participar do concurso Prefeitura de Parnamirim?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-parnamirim-rn\/#Quais_sao_as_atribuicoes_do_Guarda_de_Parnamirim\" title=\"Quais s\u00e3o as atribui\u00e7\u00f5es do Guarda de Parnamirim?\">Quais s\u00e3o as atribui\u00e7\u00f5es do Guarda de Parnamirim?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-parnamirim-rn\/#Quais_serao_as_etapas_de_selecao_do_concurso_Prefeitura_de_Parnamirim_para_Guarda\" title=\"Quais ser\u00e3o as etapas de sele\u00e7\u00e3o do concurso Prefeitura de Parnamirim para Guarda?\">Quais ser\u00e3o as etapas de sele\u00e7\u00e3o do concurso Prefeitura de Parnamirim para Guarda?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-parnamirim-rn\/#Ultimo_edital_Prefeitura_de_Parnamirim\" title=\"\u00daltimo edital Prefeitura de Parnamirim\">\u00daltimo edital Prefeitura de Parnamirim<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"situa\u00e7\u00e3o\"><span class=\"ez-toc-section\" id=\"Como_posso_me_inscrever_no_concurso_Prefeitura_de_Parnamirim\"><\/span>Como posso me inscrever no concurso Prefeitura de Parnamirim?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Os interessados em participar do certame j\u00e1 podem realizar as inscri\u00e7\u00f5es por meio do site da banca organizadora, <a href=\"https:\/\/funcern.br\/concursos\/concurso-publico-guarda-municipal-parnamirim-rn\/\" target=\"_blank\" rel=\"noreferrer noopener\">Funcern<\/a>, <strong>at\u00e9 o dia 2 de maio de 202<\/strong>4.<\/p>\n\n\n\n<p>Para que a inscri\u00e7\u00e3o seja efetivada \u00e9 necess\u00e1rio que o candidato realize o pagamento de uma taxa no valor fixo de <strong>R$ 160,00<\/strong>.<\/p>\n\n\n\n<p>Haver\u00e1 a possibilidade de solicitar a isen\u00e7\u00e3o da taxa de participa\u00e7\u00e3o <strong>at\u00e9 o dia 15 de abril de 2024<\/strong>, para os candidatos que se adequarem a uma das seguintes condi\u00e7\u00f5es:<\/p>\n\n\n\n<ol>\n<li>Se doador de sangue: Carteira de Doador ou Declara\u00e7\u00e3o emitida pelo \u00f3rg\u00e3o competente, de que efetuou, no m\u00ednimo, 03 doa\u00e7\u00f5es de sangue e, nos \u00faltimos 12 meses contados at\u00e9 o dia do in\u00edcio das inscri\u00e7\u00f5es no concurso.<\/li>\n\n\n\n<li>Se doador de medula \u00f3ssea: comprovante atualizado de cadastramento expedido por Hemocentro Regional e\/ou carteira expedida pelo Registro Nacional de Doadores Volunt\u00e1rios de Medula \u00d3ssea (REDOME) + documento de identifica\u00e7\u00e3o.<\/li>\n\n\n\n<li>Se eleitor, convocado e nomeado, que prestou servi\u00e7o \u00e0 Justi\u00e7a Eleitoral do Estado do Rio Grande do Norte.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cargos\"><span class=\"ez-toc-section\" id=\"Quantas_vagas_estao_sendo_ofertadas_no_concurso_prefeitura_de_Parnamirim-RN\"><\/span>Quantas vagas est\u00e3o sendo ofertadas no concurso prefeitura de Parnamirim-RN?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Conforme o edital, a Prefeitura de Parnamirim oferta 150 vagas, <strong>sendo 50 vagas imediatas e 100 oportunidades para forma\u00e7\u00e3o de cadastro reserva <\/strong>para o cargo de Guarda Municipal, de n\u00edvel m\u00e9dio de escolaridade.<\/p>\n\n\n\n<p>As vagas est\u00e3o distribu\u00eddas da seguinte forma:<\/p>\n\n\n\n<ul>\n<li>Ampla concorr\u00eancia: 47 vagas<\/li>\n\n\n\n<li>Pessoas com defici\u00eancia: 03<\/li>\n<\/ul>\n\n\n\n<p>A jornada de trabalho \u00e9 de 40 horas semanais para uma remunera\u00e7\u00e3o no valor de R$ 2.650,00, que ser\u00e1 acrescida por:<\/p>\n\n\n\n<ol>\n<li>Gratifica\u00e7\u00e3o de Risco de Vida no valor de R$ 946,00<\/li>\n\n\n\n<li>Adicional Noturno: R$ 120,00<\/li>\n\n\n\n<li>Adicional de Seguran\u00e7a P\u00fablica: R$ 1.250,00<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"requisitos\"><span class=\"ez-toc-section\" id=\"Quais_sao_os_requisitos_para_participar_do_concurso_Prefeitura_de_Parnamirim\"><\/span>Quais s\u00e3o os requisitos para participar do concurso Prefeitura de Parnamirim?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para que o candidato tome posse do cargo ofertado no <strong>concurso Prefeitura de Parnamirim<\/strong> \u00e9 necess\u00e1rio cumprir as seguintes exig\u00eancias:<\/p>\n\n\n\n<ul>\n<li>Possuir nacionalidade brasileira;<\/li>\n\n\n\n<li>Estar em pleno gozo dos direitos pol\u00edticos;<\/li>\n\n\n\n<li>Estar quite com as obriga\u00e7\u00f5es eleitorais e militares quando for o caso;<\/li>\n\n\n\n<li>Possuir altura m\u00ednima de 1,65m se homem e 1,60m se mulher;<\/li>\n\n\n\n<li>Possuir n\u00edvel m\u00e9dio completo de escolaridade;<\/li>\n\n\n\n<li>Ter idade m\u00ednima de 18 anos completos (com comprova\u00e7\u00e3o a ocorrer na data da posse) e idade m\u00e1xima de 35 anos (com comprova\u00e7\u00e3o na data da inscri\u00e7\u00e3o);<\/li>\n\n\n\n<li>Possuir aptid\u00e3o f\u00edsica, mental e psicol\u00f3gica para atribui\u00e7\u00e3o do cargo;<\/li>\n\n\n\n<li>Possuir Carteira Nacional de Habilita\u00e7\u00e3o, no m\u00ednimo categoria AB;<\/li>\n\n\n\n<li>Estar apto nos exames f\u00edsico, de sa\u00fade, psicol\u00f3gico e toxicol\u00f3gico de larga janela de detec\u00e7\u00e3o;<\/li>\n\n\n\n<li>Possuir idoneidade moral comprovada por investiga\u00e7\u00e3o social e certid\u00f5es expedidas pelo Poder Judici\u00e1rio estadual, federal, militar e eleitoral;<\/li>\n\n\n\n<li>Possuir conduta social ilibada;<\/li>\n\n\n\n<li>Atender demais exig\u00eancias para investidura prevista em lei;<\/li>\n\n\n\n<li>Ser aprovado no Curso de Forma\u00e7\u00e3o de Guarda Municipal.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"atribui\u00e7\u00f5es\"><span class=\"ez-toc-section\" id=\"Quais_sao_as_atribuicoes_do_Guarda_de_Parnamirim\"><\/span>Quais s\u00e3o as atribui\u00e7\u00f5es do Guarda de Parnamirim?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Confira quais s\u00e3o as atividades atribu\u00eddas ao cargo de Guarda Municipal de Parnamirim:<\/p>\n\n\n\n<ul>\n<li>Zelar pelos bens, equipamentos e pr\u00e9dios p\u00fablicos do Munic\u00edpio;<\/li>\n\n\n\n<li>Exercer a vigil\u00e2ncia diuturna e noturna interna e externa do patrim\u00f4nio p\u00fablico municipal de toda e qualquer natureza, em especial, as reparti\u00e7\u00f5es p\u00fablicas, escolas, centros municipais de educa\u00e7\u00e3o infantil, unidades de sa\u00fade, parques, pra\u00e7as, centros esportivos e culturais, demais pr\u00e9dios p\u00fablicos, com a finalidade de prevenir sinistros, atos de vandalismo e protege-los de crimes contra o patrim\u00f4nio, bem como exercer o patrulhamento preventivo e comunit\u00e1rio, promovendo a media\u00e7\u00e3o de conflitos e o respeito aos direitos fundamentais;<\/li>\n\n\n\n<li>Prevenir e inibir, pela presen\u00e7a e vigil\u00e2ncia constante, bem como coibir infra\u00e7\u00f5es penais ou administrativas e os atos infracionais que atentem contra os bens, servi\u00e7os e instala\u00e7\u00f5es municipais;<\/li>\n\n\n\n<li>Atuar, preventiva e permanentemente, no territ\u00f3rio do Munic\u00edpio, para a prote\u00e7\u00e3o sist\u00eamica da popula\u00e7\u00e3o que utiliza os bens, servi\u00e7os e instala\u00e7\u00f5es municipais;<\/li>\n\n\n\n<li>Interagir com a sociedade civil, para discuss\u00e3o de solu\u00e7\u00f5es de problemas e implementa\u00e7\u00e3o de projetos locais voltadas \u00e0 melhoria das condi\u00e7\u00f5es de seguran\u00e7a das comunidades;<\/li>\n\n\n\n<li>Atuar, de forma articulada com os \u00f3rg\u00e3os municipais de pol\u00edticas sociais, visando a\u00e7\u00f5es interdisciplinares de seguran\u00e7a, em conformidade com as diretrizes e pol\u00edticas estabelecidas pelo Poder Executivo;<\/li>\n\n\n\n<li>Exercer a Fiscaliza\u00e7\u00e3o Municipal de Tr\u00e2nsito dentro das compet\u00eancias municipais estabelecidas pelo C\u00f3digo de Tr\u00e2nsito Brasileiro, exercer a fiscaliza\u00e7\u00e3o do Sistema Municipal de Transportes na forma da legisla\u00e7\u00e3o municipal em vigor, controlar a entrada e sa\u00edda de ve\u00edculos e pessoas, bem como a orienta\u00e7\u00e3o ao p\u00fablico e seguran\u00e7a preventiva nos eventos e festividades p\u00fablicas ou privadas de interesse do Munic\u00edpio;<\/li>\n\n\n\n<li>Vigiar e proteger o patrim\u00f4nio ecol\u00f3gico, cultural, arquitet\u00f4nico e ambiental do Munic\u00edpio, apoiando medidas educativas e preventivas, escoltando as equipes de fiscaliza\u00e7\u00e3o municipal do Munic\u00edpio;<\/li>\n\n\n\n<li>Apoiar os servi\u00e7os de responsabilidade do Munic\u00edpio, incluindo sua a\u00e7\u00e3o fiscalizadora no desempenho de atividade pol\u00edtica administrativa, nos termos da Constitui\u00e7\u00e3o Federal, Constitui\u00e7\u00e3o Estadual e Lei Org\u00e2nica do Munic\u00edpio;<\/li>\n\n\n\n<li>Manter e ampliar a vigil\u00e2ncia das unidades p\u00fablicas por meio do sistema de videomonitoramento, monitoramento por alarmes e rastreamento da frota municipal;<\/li>\n\n\n\n<li>Encaminhar \u00e0 autoridade policial ou judici\u00e1ria, diante de flagrante delito, o autor da infra\u00e7\u00e3o, preservando o local dos acontecimentos e os meios de prova at\u00e9 a chegada da autoridade competente;<\/li>\n\n\n\n<li>Colaborar com os \u00f3rg\u00e3os da Defesa Civil e prestar assist\u00eancia \u00e0 popula\u00e7\u00e3o no caso de calamidade p\u00fablica;<\/li>\n\n\n\n<li>Garantir o atendimento de ocorr\u00eancias emergenciais, ou presta-lo direta e imediatamente quando deparar-se com elas;<\/li>\n\n\n\n<li>Auxiliar na seguran\u00e7a de grandes eventos e na prote\u00e7\u00e3o de autoridades e dignat\u00e1rios, inclusive prestando servi\u00e7os de escolta.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"etapas\"><span class=\"ez-toc-section\" id=\"Quais_serao_as_etapas_de_selecao_do_concurso_Prefeitura_de_Parnamirim_para_Guarda\"><\/span>Quais ser\u00e3o as etapas de sele\u00e7\u00e3o do concurso Prefeitura de Parnamirim para Guarda?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Os candidatos ser\u00e3o avaliados por meio das seguintes etapas de sele\u00e7\u00e3o:<\/p>\n\n\n\n<ol>\n<li><strong>Prova Objetiva<\/strong> &#8211; de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio;<\/li>\n\n\n\n<li><strong>Teste de Aptid\u00e3o F\u00edsica (TAF)<\/strong> &#8211; de car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Avalia\u00e7\u00e3o Psicol\u00f3gica<\/strong> &#8211; de car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Exames M\u00e9dicos<\/strong> &#8211; de car\u00e1ter eliminat\u00f3rio;<\/li>\n\n\n\n<li><strong>Investiga\u00e7\u00e3o Social<\/strong> &#8211; de car\u00e1ter eliminat\u00f3rio; e<\/li>\n\n\n\n<li><strong>Curso de Forma\u00e7\u00e3o<\/strong> &#8211; de car\u00e1ter eliminat\u00f3rio.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Prova Objetiva<\/h3>\n\n\n\n<p>Essa etapa dever\u00e1 ser realizada no dia <strong>19 de maio de 2024<\/strong> e ser\u00e1 composta por 50 quest\u00f5es de m\u00faltipla escolha que ser\u00e3o versadas nas seguintes disciplinas:<\/p>\n\n\n\n<ol>\n<li>L\u00edngua Portuguesa (10)<\/li>\n\n\n\n<li>Direito Constitucional (10)<\/li>\n\n\n\n<li>Matem\u00e1tica (05)<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direito Penal e Processual Penal (10)<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o Extravagante (15)<\/li>\n<\/ol>\n\n\n\n<p>A prova ser\u00e1 avaliada em uma escala de 0 a 100 pontos, sendo considerada aprovada a pessoa que obtiver pontua\u00e7\u00e3o m\u00ednima de 50% de acertos e n\u00e3o obtiver pontua\u00e7\u00e3o 0 na prova de qualquer uma das disciplinas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Teste de Aptid\u00e3o F\u00edsica <\/h3>\n\n\n\n<p>Nessa etapa os candidatos ser\u00e3o submetidos \u00e0s seguintes atividades:<\/p>\n\n\n\n<ol>\n<li>Flex\u00e3o de bra\u00e7os na barra fixa\n<ul>\n<li>Feminino: 10 segundos<\/li>\n\n\n\n<li>Masculino: 3 repeti\u00e7\u00f5es<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Flex\u00e3o Abdominal supra\n<ul>\n<li>Feminino: 20 repeti\u00e7\u00f5es<\/li>\n\n\n\n<li>Masculino: 25 repeti\u00e7\u00f5es<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Flex\u00e3o de bra\u00e7os sobre o solo\n<ul>\n<li>Feminino: 10 repeti\u00e7\u00f5es<\/li>\n\n\n\n<li>Masculino: 15 repeti\u00e7\u00f5es<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Corrida de 12 minutos\n<ul>\n<li>Feminino: 1.600 m<\/li>\n\n\n\n<li>Masculino: 2.000 m<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n\n\n<p>No final do teste a pessoa candidata ser\u00e1 considerada apta ou inapta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avalia\u00e7\u00e3o Psicol\u00f3gica<\/h3>\n\n\n\n<p>Essa etapa consistir\u00e1 na aplica\u00e7\u00e3o de um conjunto de procedimentos cient\u00edficos, que permitem identificar <strong>aspectos psicol\u00f3gicos<\/strong> da pessoa candidata, para fins de comprova\u00e7\u00e3o de aptid\u00e3o psicol\u00f3gica para o cargo pretendido e o manuseio de arma de fogo, atendendo \u00e0s disposi\u00e7\u00f5es t\u00e9cnicas e legais que regulam tais procedimentos.<\/p>\n\n\n\n<p>Ser\u00e3o considerados para a avalia\u00e7\u00e3o os seguintes tra\u00e7os de personalidade:<\/p>\n\n\n\n<ol>\n<li>Descontrole emocional;<\/li>\n\n\n\n<li>Descontrole da agressividade;<\/li>\n\n\n\n<li>Descontrole da impulsividade;<\/li>\n\n\n\n<li>Altera\u00e7\u00f5es acentuadas da afetividade;<\/li>\n\n\n\n<li>Oposicionismo a normas sociais e a figuras de autoridade;<\/li>\n\n\n\n<li>Dificuldade acentuada para estabelecer contato interpessoal;<\/li>\n\n\n\n<li>Funcionamento intelectual abaixo da m\u00e9dia, associado ao preju\u00edzo no comportamento adaptativo e desempenho deficit\u00e1rio de acordo com sua idade e grupamento social;<\/li>\n\n\n\n<li>Dist\u00farbio acentuado da energia vital de forma a comprometer a capacidade para a\u00e7\u00e3o.<\/li>\n<\/ol>\n\n\n\n<p>No final da avalia\u00e7\u00e3o o candidato ser\u00e1 considerado recomendado ou n\u00e3o recomendado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Exames M\u00e9dicos<\/h3>\n\n\n\n<p>Essa fase tem o objetivo de avaliar as condi\u00e7\u00f5es de sa\u00fade das pessoas candidatas.<\/p>\n\n\n\n<p>Os candidatos dever\u00e3o apresentar sob sua responsabilidade os seguintes exames:<\/p>\n\n\n\n<ol>\n<li>Radiografia do t\u00f3rax;<\/li>\n\n\n\n<li>VDRL (S\u00edfilis);<\/li>\n\n\n\n<li>Machado Guerreiro (Doen\u00e7a de Chagas);<\/li>\n\n\n\n<li>Anti-HCV (Hepatite C);<\/li>\n\n\n\n<li>Eletroencefalograma;<\/li>\n\n\n\n<li>Eletrocardiograma;<\/li>\n\n\n\n<li>Teste Audiom\u00e9trico;<\/li>\n\n\n\n<li>Hbs Ag -Hepatite B;<\/li>\n\n\n\n<li>Teste Ergom\u00e9trico (Teste da Esteira);<\/li>\n\n\n\n<li>Exame toxicol\u00f3gico de larga janela de detec\u00e7\u00e3o: m\u00ednimo de 90 dias;<\/li>\n\n\n\n<li>Outros que venham a ser julgados necess\u00e1rios conforme decis\u00e3o da comiss\u00e3o do concurso.<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Investiga\u00e7\u00e3o Social<\/h3>\n\n\n\n<p>Para a Investiga\u00e7\u00e3o, as pessoas candidatas dever\u00e3o entregar c\u00f3pias de seus documentos pessoais e outros documentos que ser\u00e3o solicitados oportunamente, bem como, para preencherem suas respectivas Fichas Individuais e de Informa\u00e7\u00f5es Confidenciais (FIIC). Esta ficha ser\u00e1 entregue a cada pessoa candidata sendo de sua responsabilidade o preenchimento e a devolu\u00e7\u00e3o no prazo estabelecido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Curso de Forma\u00e7\u00e3o<\/h3>\n\n\n\n<p>Ser\u00e1 considerada reprovada no curso de forma\u00e7\u00e3o profissional, e consequentemente eliminada do concurso, a pessoa candidata que n\u00e3o obtiver no m\u00ednimo 50% de aproveitamento nas avalia\u00e7\u00f5es aplicadas e m\u00e9dia de 60% durante o curso ou que n\u00e3o obtiver frequ\u00eancia integral.<\/p>\n\n\n\n<p>Os demais detalhes dessa etapa ser\u00e3o divulgados no edital espec\u00edfico de convoca\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"\u00faltimo\"><span class=\"ez-toc-section\" id=\"Ultimo_edital_Prefeitura_de_Parnamirim\"><\/span>\u00daltimo edital Prefeitura de Parnamirim<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O \u00faltimo edital para Guarda de Parnamirim foi publicado em 2019 e teve como banca organizadora a FUNCERN. O certame ofertou ao todo oram ofertadas 50 vagas imediatas e 150 em cadastro de reserva, distribu\u00eddas entre candidatos do sexo masculino e feminino.<\/p>\n\n\n\n<p>Os candidatos foram avaliados por meio de seis etapas:<\/p>\n\n\n\n<ol>\n<li><strong>Prova objetiva<\/strong> &#8211; de car\u00e1ter <em>eliminat\u00f3rio <\/em>e <em>classificat\u00f3rio<\/em><\/li>\n\n\n\n<li><strong>Teste de Aptid\u00e3o F\u00edsica<\/strong> &#8211; de car\u00e1ter <em>eliminat\u00f3rio<\/em><\/li>\n\n\n\n<li><strong>Avalia\u00e7\u00e3o Psicol\u00f3gica <\/strong>&#8211; de car\u00e1ter <em>eliminat\u00f3rio<\/em><\/li>\n\n\n\n<li><strong>Investiga\u00e7\u00e3o Social<\/strong> &#8211; de car\u00e1ter <em>eliminat\u00f3rio<\/em><\/li>\n\n\n\n<li><strong>Curso de Forma\u00e7\u00e3o Profissional<\/strong> &#8211; de car\u00e1ter <em>eliminat\u00f3rio<\/em><\/li>\n\n\n\n<li><strong>Apresenta\u00e7\u00e3o de Exames M\u00e9dicos<\/strong> &#8211; de car\u00e1ter <em>eliminat\u00f3rio<\/em><\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Prova objetiva<\/h3>\n\n\n\n<p>Essa etapa foi composta por 50 quest\u00f5es de m\u00faltipla escolha que foram versadas nas seguintes disciplinas:<\/p>\n\n\n\n<ul>\n<li>L\u00edngua Portuguesa (10 quest\u00f5es);<\/li>\n\n\n\n<li>Direito Constitucional (10 quest\u00f5es);<\/li>\n\n\n\n<li>Matem\u00e1tica (10 quest\u00f5es);<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Direito Penal e Processual Penal (5 quest\u00f5es);<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o de Tr\u00e2nsito (10 quest\u00f5es);<\/li>\n\n\n\n<li>Inform\u00e1tica (5 quest\u00f5es).<\/li>\n<\/ul>\n\n\n\n<p>A avalia\u00e7\u00e3o foi avaliada em uma escala de 0 a 100 pontos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Teste de Aptid\u00e3o F\u00edsica<\/h3>\n\n\n\n<p>Essa fase foi realizada em dois dias, onde os candidatos tiveram qeu realizar as seguintes atividades:<\/p>\n\n\n\n<ul>\n<li><strong>1\u00ba dia<\/strong>:\n<ul>\n<li>Corrida de 12 minutos: \n<ul>\n<li>Sexo masculino: 2.000m<\/li>\n\n\n\n<li>Sexo feminino: 1.600m <\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Flex\u00e3o de bra\u00e7os na barra fixa: \n<ul>\n<li>Homens: 3 repeti\u00e7\u00f5es em 20 segundos<\/li>\n\n\n\n<li>Mulheres: 1 suspens\u00e3o em 10 segundos<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>2\u00ba dia<\/strong>:\n<ul>\n<li>Flex\u00e3o de bra\u00e7os sobre o solo: \n<ul>\n<li>Sexo masculino: 19 repeti\u00e7\u00f5es <\/li>\n\n\n\n<li>Sexo feminino: 10 repeti\u00e7\u00f5es<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Abdominal supra: \n<ul>\n<li>Homens: 30 repeti\u00e7\u00f5es em no m\u00e1ximo 3 minutos <\/li>\n\n\n\n<li>Mulheres: 27 repeti\u00e7\u00f5es em no m\u00e1ximo de 3 minutos <\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p>O prazo de <strong>validade <\/strong>deste Concurso P\u00fablico ser\u00e1 de dois anos contados a partir da data de publica\u00e7\u00e3o da homologa\u00e7\u00e3o do Resultado Final no Di\u00e1rio Oficial de Parnamirim\/RN, podendo ser prorrogado uma \u00fanica vez, por mais dois anos.<\/p>\n\n\n\n<p><strong>Bons estudos e boa prova!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1 concurseiros do Rio Grande do Norte! Foi publicado o edital do concurso Prefeitura de Parnamirim, que oferta 150 vagas para provimento imediato e para forma\u00e7\u00e3o de cadastro reserva para o cargo de Guarda. Se interessa pelo certame? Fique e confira os demais detalhes no decorrer da not\u00edcia. \ud83d\ude09 Como posso me inscrever no concurso Prefeitura de Parnamirim? Os interessados em participar do certame j\u00e1 podem realizar as inscri\u00e7\u00f5es por meio do site da banca organizadora, Funcern, at\u00e9 o dia 2 de maio de 2024. Para que a inscri\u00e7\u00e3o seja efetivada \u00e9 necess\u00e1rio que o candidato realize o pagamento de&#8230;<\/p>\n","protected":false},"author":18,"featured_media":40923,"template":"","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false},"categories":[],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/concurso\/2048"}],"collection":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/concurso"}],"about":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/types\/concurso"}],"author":[{"embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/users\/18"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/media\/40923"}],"wp:attachment":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}