{"id":3587,"date":"2019-05-29T16:35:01","date_gmt":"2019-05-29T19:35:01","guid":{"rendered":"https:\/\/www.editorasolucao.com.br\/blog\/?post_type=concurso&#038;p=3587"},"modified":"2019-06-16T23:40:37","modified_gmt":"2019-06-17T02:40:37","slug":"prefeitura-de-cristina-mg","status":"publish","type":"concurso","link":"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-cristina-mg","title":{"rendered":"Concurso Prefeitura de Cristina &#8211; MG 2019: Mais de 40 vagas para todos os n\u00edveis!"},"content":{"rendered":"\n<p>Saiu o <a href=\"http:\/\/www.editorasolucao.com.br\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"edital  (abre em uma nova aba)\">edital <\/a>do concurso Prefeitura de Cristina em <a rel=\"noreferrer noopener\" aria-label=\" (abre em uma nova aba)\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concursos-abertos-mg\" target=\"_blank\">Minas Gerais <\/a>com <strong>45 oportunidades<\/strong> para candidatos de <strong>todos os n\u00edveis<\/strong> de escolaridade e sal\u00e1rios que chegam a <strong>R$ 2,9 mil<\/strong>!<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_69_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Menu de navega&ccedil;&atilde;o<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-cristina-mg\/#Inscricoes_do_concurso_Prefeitura_de_Cristina\" title=\"Inscri\u00e7\u00f5es do concurso Prefeitura de Cristina\">Inscri\u00e7\u00f5es do concurso Prefeitura de Cristina<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-cristina-mg\/#Cargos_vagas_e_salarios_do_concurso\" title=\"Cargos, vagas e sal\u00e1rios do concurso\">Cargos, vagas e sal\u00e1rios do concurso<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.editorasolucao.com.br\/blog\/concurso\/prefeitura-de-cristina-mg\/#Como_serao_as_provas_do_concurso\" title=\"Como ser\u00e3o as provas do concurso?\">Como ser\u00e3o as provas do concurso?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Inscricoes_do_concurso_Prefeitura_de_Cristina\"><\/span><strong>Inscri\u00e7\u00f5es do concurso Prefeitura de Cristina<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para participar, acesse o site da banca organizadora, <a rel=\"noreferrer noopener\" aria-label=\"IMAM (abre em uma nova aba)\" href=\"http:\/\/www.imamconcursos.org.br\/sitenoticia\/processo_seletivo_detalhes.aspx?id=DA9C60666FA142CE\" target=\"_blank\">IMAM<\/a>, a partir do dia <strong>07 de agosto at\u00e9 o dia 06 de setembro de 2019<\/strong>. As taxas variam de <strong>R$ 46,00 a R$ 96,00<\/strong>.<\/p>\n\n\n\n<p>Confira todos os detalhes sobre o concurso para que voc\u00ea possa iniciar sua prepara\u00e7\u00e3o.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cargos_vagas_e_salarios_do_concurso\"><\/span><strong>Cargos, vagas e sal\u00e1rios do concurso <\/strong><br><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>As oportunidades est\u00e3o divididas entre os seguintes cargos:<\/p>\n\n\n\n<p>Ajudante de Servi\u00e7os Gerais (2); Auxiliar de Servi\u00e7os Gerais (5); Motorista (4); Oficial de Servi\u00e7os Especializados (2); Auxiliar Administrativo (2); Agente Administrativo II (1); Fiscal de Obras, Patrim\u00f4nio e Postura (1); Eletricista (1); T\u00e9cnico de Enfermagem (1); Assistente Social (1); Nutricionista (1); Psic\u00f3logo (1) e Professores da Educa\u00e7\u00e3o B\u00e1sica II (15), Educa\u00e7\u00e3o B\u00e1sica II &#8211; AEE (1), Educa\u00e7\u00e3o B\u00e1sica III &#8211; Educa\u00e7\u00e3o F\u00edsica (2), Geografia (1), Hist\u00f3ria\/ Educa\u00e7\u00e3o Patrimonial (1), L\u00edngua Inglesa (1), L\u00edngua Portuguesa (1) e Matem\u00e1tica (1).<\/p>\n\n\n\n<p>A remunera\u00e7\u00e3o inicial varia, dependendo do cargo, de <strong>R$ 998,00 a R$&nbsp;2.924,27<\/strong>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_serao_as_provas_do_concurso\"><\/span><strong>Como ser\u00e3o as provas do concurso?<\/strong><br><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>O processo de avalia\u00e7\u00e3o dos candidatos se dar\u00e1 por meio de prova objetiva (para todos os cargos) e de reda\u00e7\u00e3o (somente para os cargos de Professor) a ser aplicadas nos dias <strong>12 e 13 de outubro de 2019<\/strong>. <\/p>\n\n\n\n<p>Os locais e hor\u00e1rios de prova ser\u00e3o divulgados no site da organizadora a partir do dia 25 de setembro. As provas contar\u00e3o com as disciplinas de:<\/p>\n\n\n\n<ul><li>Portugu\u00eas;<\/li><li>Matem\u00e1tica;<\/li><li>Sistema \u00danico de Sa\u00fade\/Sa\u00fade P\u00fablica (somente para cargos de n\u00edvel superior);<\/li><li>Teoria e Pr\u00e1tica da Educa\u00e7\u00e3o (somente para o cargo de Professor);<\/li><li>Conhecimentos Espec\u00edficos.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Saiu o edital do concurso Prefeitura de Cristina em Minas Gerais com 45 oportunidades para candidatos de todos os n\u00edveis de escolaridade e sal\u00e1rios que chegam a R$ 2,9 mil! Inscri\u00e7\u00f5es do concurso Prefeitura de Cristina Para participar, acesse o site da banca organizadora, IMAM, a partir do dia 07 de agosto at\u00e9 o dia 06 de setembro de 2019. As taxas variam de R$ 46,00 a R$ 96,00. Confira todos os detalhes sobre o concurso para que voc\u00ea possa iniciar sua prepara\u00e7\u00e3o. Cargos, vagas e sal\u00e1rios do concurso As oportunidades est\u00e3o divididas entre os seguintes cargos: Ajudante de Servi\u00e7os&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2749,"template":"","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false},"categories":[],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/concurso\/3587"}],"collection":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/concurso"}],"about":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/types\/concurso"}],"author":[{"embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/media\/2749"}],"wp:attachment":[{"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.editorasolucao.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}